{"id":1610,"date":"2025-10-07T15:37:32","date_gmt":"2025-10-07T18:37:32","guid":{"rendered":"https:\/\/nacuia.org\/?p=1610"},"modified":"2025-10-31T12:14:04","modified_gmt":"2025-10-31T15:14:04","slug":"comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta","status":"publish","type":"post","link":"https:\/\/nacuia.org\/en\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/","title":{"rendered":"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1610\" class=\"elementor elementor-1610\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e79e71a e-flex e-con-boxed e-con e-parent\" data-id=\"e79e71a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-053f6c0 elementor-widget elementor-widget-heading\" data-id=\"053f6c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5eae8a95 elementor-widget elementor-widget-text-editor\" data-id=\"5eae8a95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"has-text-align-left\">Clima, cultura, comunica\u00e7\u00e3o e bem viver foram os temas debatidos na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta, realizado na \u00faltima quinta-feira, 02 de outubro, no Palacete Faciola, em Bel\u00e9m. O encontro &#8211; que tamb\u00e9m reuniu lideran\u00e7as sociais, artistas, pesquisadores e ativistas &#8211; teve forte presen\u00e7a de comunicadores populares do Comit\u00ea das Baixadas de Bel\u00e9m, que levaram ao centro da conversa a import\u00e2ncia da democratiza\u00e7\u00e3o da informa\u00e7\u00e3o e do combate \u00e0 desinforma\u00e7\u00e3o ambiental.<\/p>\n<p class=\"has-text-align-left\">\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>O <strong>F\u00f3rum Ambienta faz parte do Festival Ambienta<\/strong>, sendo um espa\u00e7o de di\u00e1logo e reflex\u00f5es sobre quest\u00f5es ambientais, clim\u00e1ticas e sobre o papel da cultura na promo\u00e7\u00e3o da sustentabilidade. Na edi\u00e7\u00e3o deste ano, que abordou o tema <strong>\u201cIntegridade da Informa\u00e7\u00e3o e Solu\u00e7\u00f5es Populares para o Clima\u201d<\/strong>, o encontro prop\u00f4s reflex\u00f5es sobre os desafios da crise clim\u00e1tica e o papel da sociedade civil na constru\u00e7\u00e3o de respostas criativas, interseccionais e enraizadas nos territ\u00f3rios.<\/p>\n<p>\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<h6><strong>Comunica\u00e7\u00e3o Popular na pauta clim\u00e1tica<\/strong><\/h6>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>No 4\u00ba F\u00f3rum, os comunicadores do Comit\u00ea das Baixadas de Bel\u00e9m estiveram nas mesas de debates, trazendo mais exemplos de a\u00e7\u00f5es, mobiliza\u00e7\u00f5es e solu\u00e7\u00f5es populares para o enfrentamento da crise clim\u00e1tica, tendo como base as iniciativas desenvolvidas em seus territ\u00f3rios.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>\u201cQuando falamos em solu\u00e7\u00f5es, estamos falando de pr\u00e1ticas reais, feitas nos territ\u00f3rios\u201d, afirmou o comunicador Matheus Botelho, que atuou como curador do evento. Para ele, a comunica\u00e7\u00e3o popular mostra que \u00e9 poss\u00edvel transformar o cuidado com o clima em a\u00e7\u00e3o coletiva. \u201c\u00c9 por meio do artivismo, das solu\u00e7\u00f5es clim\u00e1ticas populares e das iniciativas comunit\u00e1rias que buscamos mostrar \u00e0 popula\u00e7\u00e3o que, juntos, conseguimos encontrar caminhos e fazer a nossa parte, n\u00e3o apenas de forma individual, mas como parte de um coletivo maior\u201d, pontuou.<\/p>\n<p>\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<h6><strong>Debates, arte e cultura no F\u00f3rum Ambienta<\/strong><\/h6>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>O evento iniciou com o Ato Po\u00e9tico \u201cPor uma Amaz\u00f4nia Viva\u201d, realizado pela artivista e maraqueira, Samara Cheetara, integrante da Associa\u00e7\u00e3o Cultural Na Cuia, e Jam Bill, artista m\u00faltipla, educadora e brincante da cultura popular. Atravessando o espa\u00e7o em cortejo com canto, poesia e elementos da natureza, a performance entrela\u00e7ou encantaria e saberes ancestrais em di\u00e1logo com a urg\u00eancia do tempo presente. Em seus cantos, as artistas ecoaram hist\u00f3rias que denunciam os impactos da crise clim\u00e1tica sobre a floresta e os povos que dela vivem e afirmaram a for\u00e7a dos povos da Amaz\u00f4nia.<\/p>\n<p>\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>A mesa \u201cArtivismo e Solu\u00e7\u00f5es Clim\u00e1ticas Populares\u201d abriu os di\u00e1logos do f\u00f3rum, sendo composta por Maria Flor, designer de moda e ativista do coletivo Casa Cura; Jo\u00e3o do Clima, jovem ativista da ilha de Caratateua e conselheiro jovem da UNICEF; Aline Gama, comunicadora e educadora popular, integrante do Coletivo Miri (Castanhal); e Alex Soares, Assessor de agenda pol\u00edtica na Palmares Laborat\u00f3rio-A\u00e7\u00e3o. A mesa teve o objetivo de discutir como a cultura, a criatividade e as pr\u00e1ticas comunit\u00e1rias enfrentam os impactos ambientais de forma justa e inovadora.<\/p>\n<p>\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>A segunda mesa do encontro teve como tema \u201cIntegridade da Informa\u00e7\u00e3o pelo Clima\u201d e abordou os riscos da desinforma\u00e7\u00e3o, do negacionismo e da concentra\u00e7\u00e3o midi\u00e1tica, e como mulheres e pessoas trans da Amaz\u00f4nia t\u00eam protagonizado a luta pela democracia e pela justi\u00e7a clim\u00e1tica. A mesa foi composta por Paulie Amaral, comunicadora popular, gestora e ativista clim\u00e1tica na Amaz\u00f4nia; Jessica Botelho, jornalista e pesquisadora; Fl\u00e1via Ribeiro, jornalista e assessora de imprensa; e Juliana Mori, diretora editorial da InfoAmazonia.<\/p>\n<p>\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Em sua fala, Paulie Amaral, integrante da Na Cuia e do Comit\u00ea de comunicadores populares, destacou a import\u00e2ncia da constru\u00e7\u00e3o coletiva e de manter a comunica\u00e7\u00e3o como ferramenta de resist\u00eancia. \u201cO que a gente tem de mais forte \u00e9 a coletividade. \u00c9 da\u00ed que vem a comunica\u00e7\u00e3o, e \u00e9 da\u00ed que surgem as outras formas de construir juntos, e \u00e9 justamente por isso que o sistema n\u00e3o quer que a gente esteja unido, porque sabe que quando a gente se une, alguma coisa acontece. A gente viu isso recentemente, com a manifesta\u00e7\u00e3o contra a PEC da Blindagem (ou, como muitos chamaram, da Bandidagem). Muita gente foi \u00e0s ruas, e esse tipo de mobiliza\u00e7\u00e3o \u00e9 muito perigoso para quem est\u00e1 no poder\u201d, frisou.<\/p>\n<p>\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Al\u00e9m disso, para a comunicadora, a comunica\u00e7\u00e3o popular \u00e9 mais que uma ferramenta de divulga\u00e7\u00e3o, ela \u00e9 tamb\u00e9m uma estrat\u00e9gia de resist\u00eancia diante das desigualdades: \u201cA comunica\u00e7\u00e3o popular \u00e9 esse ambiente seguro, de acolhimento e cuidado, onde nossas narrativas s\u00e3o valorizadas e n\u00e3o vivem em constante disputa, como \u00e9 o que a gente enfrenta todos os dias\u201d.<\/p>\n<p>\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Durante a programa\u00e7\u00e3o do F\u00f3rum, o p\u00fablico tamb\u00e9m acompanhou o Duelo pelo Clima, realizando entre os intervalos das mesas, com os rappers Moraes MV e Bruna BG, trazendo o debate ambiental para o universo do hip hop e das batalhas de rima.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph {\"align\":\"left\"} --><\/p>\n<p class=\"has-text-align-left\">O encerramento cultural ficou por conta do Grupo de Carimb\u00f3 Africanos de Icoaraci, sob a lideran\u00e7a do Mestre Thomaz Cruz, celebrando a for\u00e7a da cultura popular amaz\u00f4nica como resist\u00eancia e mem\u00f3ria viva.<\/p>\n<p class=\"has-text-align-left\">\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph {\"align\":\"left\"} --><\/p>\n<p class=\"has-text-align-left\">O <strong>Comit\u00ea de Comunicadores Populares das Baixadas de Bel\u00e9m<\/strong>, \u00e9 iniciativa da <strong>Associa\u00e7\u00e3o Cultural Na Cuia<\/strong>, e surge para fortalecer as vozes perif\u00e9ricas diante dos desafios sociais, ambientais e culturais da Amaz\u00f4nia. Inspirado na tradi\u00e7\u00e3o hist\u00f3rica dos comit\u00eas de comunica\u00e7\u00e3o popular, o movimento re\u00fane jovens, artistas, comunicadores, ind\u00edgenas, quilombolas, comunidades tradicionais e pessoas LGBTQIAPN+ que vivem e produzem na regi\u00e3o metropolitana de Bel\u00e9m do Par\u00e1.<\/p>\n<p class=\"has-text-align-left\">\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph {\"align\":\"left\"} --><\/p>\n<p class=\"has-text-align-left\">O Comit\u00ea promove forma\u00e7\u00f5es t\u00e9cnicas e pol\u00edticas, articulando comunica\u00e7\u00e3o popular, jornalismo de causa e incid\u00eancia territorial. O projeto atua no enfrentamento ao racismo ambiental com a defesa dos territ\u00f3rios amaz\u00f4nicos e na amplia\u00e7\u00e3o da presen\u00e7a midi\u00e1tica de base comunit\u00e1ria, formando uma nova gera\u00e7\u00e3o de comunicadores comprometidos com as pautas da <strong>COP 30 e al\u00e9m dela<\/strong>, comunicadores que narram o futuro com o prop\u00f3sito de dar visibilidade \u00e0s lutas por justi\u00e7a clim\u00e1tica e social e preservar as culturas e saberes ancestrais.<\/p>\n<p class=\"has-text-align-left\">\u00a0<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><em><strong>Reda\u00e7\u00e3o: <\/strong>L\u00edrio Moraes, Na Cuia<\/em><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78e543a e-flex e-con-boxed e-con e-parent\" data-id=\"78e543a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta Clima, cultura, comunica\u00e7\u00e3o e bem viver foram os temas debatidos na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta, realizado na \u00faltima quinta-feira, 02 de outubro, no Palacete Faciola, em Bel\u00e9m. O encontro &#8211; que tamb\u00e9m reuniu lideran\u00e7as sociais, artistas, pesquisadores e ativistas &#8211; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[11],"class_list":["post-1610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta - NA CUIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nacuia.org\/en\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta - NA CUIA\" \/>\n<meta property=\"og:description\" content=\"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta Clima, cultura, comunica\u00e7\u00e3o e bem viver foram os temas debatidos na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta, realizado na \u00faltima quinta-feira, 02 de outubro, no Palacete Faciola, em Bel\u00e9m. O encontro &#8211; que tamb\u00e9m reuniu lideran\u00e7as sociais, artistas, pesquisadores e ativistas &#8211; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nacuia.org\/en\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/\" \/>\n<meta property=\"og:site_name\" content=\"NA CUIA\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-07T18:37:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T15:14:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nacuia.org\/wp-content\/uploads\/2025\/10\/0X2A1590-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"L\u00edrio Moraes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"L\u00edrio Moraes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/\"},\"author\":{\"name\":\"L\u00edrio Moraes\",\"@id\":\"https:\\\/\\\/nacuia.org\\\/#\\\/schema\\\/person\\\/34c604c26c294e17c3fef863fefc6aa1\"},\"headline\":\"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta\",\"datePublished\":\"2025-10-07T18:37:32+00:00\",\"dateModified\":\"2025-10-31T15:14:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/\"},\"wordCount\":1087,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nacuia.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/0X2A1590-scaled.jpg\",\"keywords\":[\"Noticias\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/\",\"url\":\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/\",\"name\":\"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta - NA CUIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nacuia.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nacuia.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/0X2A1590-scaled.jpg\",\"datePublished\":\"2025-10-07T18:37:32+00:00\",\"dateModified\":\"2025-10-31T15:14:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nacuia.org\\\/#\\\/schema\\\/person\\\/34c604c26c294e17c3fef863fefc6aa1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nacuia.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/0X2A1590-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/nacuia.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/0X2A1590-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Comunicadores populares marcaram forte presen\u00e7a no evento Foto: Bruno Carachesti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nacuia.org\\\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/nacuia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nacuia.org\\\/#website\",\"url\":\"https:\\\/\\\/nacuia.org\\\/\",\"name\":\"NA CUIA\",\"description\":\"Associa\u00e7\u00e3o Cultural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nacuia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nacuia.org\\\/#\\\/schema\\\/person\\\/34c604c26c294e17c3fef863fefc6aa1\",\"name\":\"L\u00edrio Moraes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9241ea53a1ab433571c41836c94c6550cd320a90cad2dcbede7dc5f52dd38230?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9241ea53a1ab433571c41836c94c6550cd320a90cad2dcbede7dc5f52dd38230?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9241ea53a1ab433571c41836c94c6550cd320a90cad2dcbede7dc5f52dd38230?s=96&d=mm&r=g\",\"caption\":\"L\u00edrio Moraes\"},\"url\":\"https:\\\/\\\/nacuia.org\\\/en\\\/author\\\/lirio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta - NA CUIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nacuia.org\/en\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/","og_locale":"en_US","og_type":"article","og_title":"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta - NA CUIA","og_description":"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta Clima, cultura, comunica\u00e7\u00e3o e bem viver foram os temas debatidos na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta, realizado na \u00faltima quinta-feira, 02 de outubro, no Palacete Faciola, em Bel\u00e9m. O encontro &#8211; que tamb\u00e9m reuniu lideran\u00e7as sociais, artistas, pesquisadores e ativistas &#8211; [&hellip;]","og_url":"https:\/\/nacuia.org\/en\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/","og_site_name":"NA CUIA","article_published_time":"2025-10-07T18:37:32+00:00","article_modified_time":"2025-10-31T15:14:04+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/nacuia.org\/wp-content\/uploads\/2025\/10\/0X2A1590-scaled.jpg","type":"image\/jpeg"}],"author":"L\u00edrio Moraes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"L\u00edrio Moraes","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/#article","isPartOf":{"@id":"https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/"},"author":{"name":"L\u00edrio Moraes","@id":"https:\/\/nacuia.org\/#\/schema\/person\/34c604c26c294e17c3fef863fefc6aa1"},"headline":"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta","datePublished":"2025-10-07T18:37:32+00:00","dateModified":"2025-10-31T15:14:04+00:00","mainEntityOfPage":{"@id":"https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/"},"wordCount":1087,"commentCount":0,"image":{"@id":"https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/#primaryimage"},"thumbnailUrl":"https:\/\/nacuia.org\/wp-content\/uploads\/2025\/10\/0X2A1590-scaled.jpg","keywords":["Noticias"],"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/","url":"https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/","name":"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta - NA CUIA","isPartOf":{"@id":"https:\/\/nacuia.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/#primaryimage"},"image":{"@id":"https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/#primaryimage"},"thumbnailUrl":"https:\/\/nacuia.org\/wp-content\/uploads\/2025\/10\/0X2A1590-scaled.jpg","datePublished":"2025-10-07T18:37:32+00:00","dateModified":"2025-10-31T15:14:04+00:00","author":{"@id":"https:\/\/nacuia.org\/#\/schema\/person\/34c604c26c294e17c3fef863fefc6aa1"},"breadcrumb":{"@id":"https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/#primaryimage","url":"https:\/\/nacuia.org\/wp-content\/uploads\/2025\/10\/0X2A1590-scaled.jpg","contentUrl":"https:\/\/nacuia.org\/wp-content\/uploads\/2025\/10\/0X2A1590-scaled.jpg","width":2560,"height":1707,"caption":"Comunicadores populares marcaram forte presen\u00e7a no evento Foto: Bruno Carachesti"},{"@type":"BreadcrumbList","@id":"https:\/\/nacuia.org\/comunicadores-populares-protagonizam-debates-sobre-clima-e-desinformacao-na-4a-edicao-do-forum-ambienta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nacuia.org\/"},{"@type":"ListItem","position":2,"name":"Comunicadores populares protagonizam debates sobre clima e desinforma\u00e7\u00e3o na 4\u00aa edi\u00e7\u00e3o do F\u00f3rum Ambienta"}]},{"@type":"WebSite","@id":"https:\/\/nacuia.org\/#website","url":"https:\/\/nacuia.org\/","name":"NA CUIA","description":"Associa\u00e7\u00e3o Cultural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nacuia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nacuia.org\/#\/schema\/person\/34c604c26c294e17c3fef863fefc6aa1","name":"L\u00edrio Moraes","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9241ea53a1ab433571c41836c94c6550cd320a90cad2dcbede7dc5f52dd38230?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9241ea53a1ab433571c41836c94c6550cd320a90cad2dcbede7dc5f52dd38230?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9241ea53a1ab433571c41836c94c6550cd320a90cad2dcbede7dc5f52dd38230?s=96&d=mm&r=g","caption":"L\u00edrio Moraes"},"url":"https:\/\/nacuia.org\/en\/author\/lirio\/"}]}},"_links":{"self":[{"href":"https:\/\/nacuia.org\/en\/wp-json\/wp\/v2\/posts\/1610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nacuia.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nacuia.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nacuia.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nacuia.org\/en\/wp-json\/wp\/v2\/comments?post=1610"}],"version-history":[{"count":19,"href":"https:\/\/nacuia.org\/en\/wp-json\/wp\/v2\/posts\/1610\/revisions"}],"predecessor-version":[{"id":1982,"href":"https:\/\/nacuia.org\/en\/wp-json\/wp\/v2\/posts\/1610\/revisions\/1982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nacuia.org\/en\/wp-json\/wp\/v2\/media\/1612"}],"wp:attachment":[{"href":"https:\/\/nacuia.org\/en\/wp-json\/wp\/v2\/media?parent=1610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nacuia.org\/en\/wp-json\/wp\/v2\/categories?post=1610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nacuia.org\/en\/wp-json\/wp\/v2\/tags?post=1610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}